{"id":379,"date":"2026-08-31T21:58:17","date_gmt":"2026-08-31T19:58:17","guid":{"rendered":"https:\/\/somosardo.com\/projectes\/anillo-de-fuego\/"},"modified":"2026-09-02T18:43:56","modified_gmt":"2026-09-02T16:43:56","slug":"anillo-de-fuego","status":"publish","type":"projecte","link":"https:\/\/somosardo.com\/es\/projectes\/anillo-de-fuego\/","title":{"rendered":"Anillo de fuego"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Sinopsis<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Anna Dot aprendi\u00f3 a fundir oro para hacer los anillos de su boda. Lo aprendi\u00f3 en una semana, guiada por Cristina, en el taller de Maba Joies, en Vic.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pol Aregall lo film\u00f3 en s\u00faper 8, entre el taller y el r\u00edo Ter a su paso por Torell\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los anillos se terminaron. Se casaron. Un mes m\u00e1s tarde nac\u00eda Joana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La banda sonora llega despu\u00e9s. Es una nota de voz donde Anna pregunta a Joana, de cuatro meses, c\u00f3mo har\u00eda un hechizo. Juana responde con sonidos que todav\u00eda no son palabras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"featured_media":383,"menu_order":1,"template":"","class_list":["post-379","projecte","type-projecte","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Anillo de fuego &#183; Ardo Productions<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anillo de fuego &#183; Ardo Productions\" \/>\n<meta property=\"og:description\" content=\"Sinopsis Anna Dot aprendi\u00f3 a fundir oro para hacer los anillos de su boda. Lo aprendi\u00f3 en una semana, guiada por Cristina, en el taller de Maba Joies, en Vic. Pol Aregall lo film\u00f3 en s\u00faper 8, entre el taller y el r\u00edo Ter a su paso por Torell\u00f3. Los anillos se terminaron. Se casaron. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/somosardo.com\/es\/projectes\/anillo-de-fuego\/\" \/>\n<meta property=\"og:site_name\" content=\"Ardo Productions\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T16:43:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/somosardo.com\/wp-content\/uploads\/2026\/06\/Anillo-de-fuego-Portada-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/somosardo.com\\\/es\\\/projectes\\\/anillo-de-fuego\\\/\",\"url\":\"https:\\\/\\\/somosardo.com\\\/es\\\/projectes\\\/anillo-de-fuego\\\/\",\"name\":\"Anillo de fuego &#183; Ardo Productions\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/somosardo.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/somosardo.com\\\/es\\\/projectes\\\/anillo-de-fuego\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/somosardo.com\\\/es\\\/projectes\\\/anillo-de-fuego\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/somosardo.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Anillo-de-fuego-Portada-scaled.jpg\",\"datePublished\":\"2026-08-31T19:58:17+00:00\",\"dateModified\":\"2026-09-02T16:43:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/somosardo.com\\\/es\\\/projectes\\\/anillo-de-fuego\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/somosardo.com\\\/es\\\/projectes\\\/anillo-de-fuego\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/somosardo.com\\\/es\\\/projectes\\\/anillo-de-fuego\\\/#primaryimage\",\"url\":\"https:\\\/\\\/somosardo.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Anillo-de-fuego-Portada-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/somosardo.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Anillo-de-fuego-Portada-scaled.jpg\",\"width\":2560,\"height\":1440,\"caption\":\"Fotograma en s\u00faper 8: una m\u00e0 toca l'aigua del riu Ter, amb el t\u00edtol Anillo de fuego en vermell\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/somosardo.com\\\/es\\\/projectes\\\/anillo-de-fuego\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/somosardo.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projectes\",\"item\":\"https:\\\/\\\/somosardo.com\\\/es\\\/projectes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Anillo de fuego\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/somosardo.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/somosardo.com\\\/es\\\/\",\"name\":\"Ardo Productions\",\"description\":\"Productora audiovisual\",\"publisher\":{\"@id\":\"https:\\\/\\\/somosardo.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/somosardo.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/somosardo.com\\\/es\\\/#organization\",\"name\":\"Ardo Productions\",\"url\":\"https:\\\/\\\/somosardo.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/somosardo.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/somosardo.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/favicon.png\",\"contentUrl\":\"https:\\\/\\\/somosardo.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/favicon.png\",\"width\":600,\"height\":600,\"caption\":\"Ardo Productions\"},\"image\":{\"@id\":\"https:\\\/\\\/somosardo.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/ardoproductions\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@ARDO_PRODUCTIONS\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anillo de fuego &#183; Ardo Productions","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"Anillo de fuego &#183; Ardo Productions","og_description":"Sinopsis Anna Dot aprendi\u00f3 a fundir oro para hacer los anillos de su boda. Lo aprendi\u00f3 en una semana, guiada por Cristina, en el taller de Maba Joies, en Vic. Pol Aregall lo film\u00f3 en s\u00faper 8, entre el taller y el r\u00edo Ter a su paso por Torell\u00f3. Los anillos se terminaron. Se casaron. [&hellip;]","og_url":"https:\/\/somosardo.com\/es\/projectes\/anillo-de-fuego\/","og_site_name":"Ardo Productions","article_modified_time":"2026-09-02T16:43:56+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/somosardo.com\/wp-content\/uploads\/2026\/06\/Anillo-de-fuego-Portada-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/somosardo.com\/es\/projectes\/anillo-de-fuego\/","url":"https:\/\/somosardo.com\/es\/projectes\/anillo-de-fuego\/","name":"Anillo de fuego &#183; Ardo Productions","isPartOf":{"@id":"https:\/\/somosardo.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/somosardo.com\/es\/projectes\/anillo-de-fuego\/#primaryimage"},"image":{"@id":"https:\/\/somosardo.com\/es\/projectes\/anillo-de-fuego\/#primaryimage"},"thumbnailUrl":"https:\/\/somosardo.com\/wp-content\/uploads\/2026\/06\/Anillo-de-fuego-Portada-scaled.jpg","datePublished":"2026-08-31T19:58:17+00:00","dateModified":"2026-09-02T16:43:56+00:00","breadcrumb":{"@id":"https:\/\/somosardo.com\/es\/projectes\/anillo-de-fuego\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/somosardo.com\/es\/projectes\/anillo-de-fuego\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/somosardo.com\/es\/projectes\/anillo-de-fuego\/#primaryimage","url":"https:\/\/somosardo.com\/wp-content\/uploads\/2026\/06\/Anillo-de-fuego-Portada-scaled.jpg","contentUrl":"https:\/\/somosardo.com\/wp-content\/uploads\/2026\/06\/Anillo-de-fuego-Portada-scaled.jpg","width":2560,"height":1440,"caption":"Fotograma en s\u00faper 8: una m\u00e0 toca l'aigua del riu Ter, amb el t\u00edtol Anillo de fuego en vermell"},{"@type":"BreadcrumbList","@id":"https:\/\/somosardo.com\/es\/projectes\/anillo-de-fuego\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/somosardo.com\/es\/"},{"@type":"ListItem","position":2,"name":"Projectes","item":"https:\/\/somosardo.com\/es\/projectes\/"},{"@type":"ListItem","position":3,"name":"Anillo de fuego"}]},{"@type":"WebSite","@id":"https:\/\/somosardo.com\/es\/#website","url":"https:\/\/somosardo.com\/es\/","name":"Ardo Productions","description":"Productora audiovisual","publisher":{"@id":"https:\/\/somosardo.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/somosardo.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/somosardo.com\/es\/#organization","name":"Ardo Productions","url":"https:\/\/somosardo.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/somosardo.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/somosardo.com\/wp-content\/uploads\/2026\/06\/favicon.png","contentUrl":"https:\/\/somosardo.com\/wp-content\/uploads\/2026\/06\/favicon.png","width":600,"height":600,"caption":"Ardo Productions"},"image":{"@id":"https:\/\/somosardo.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/ardoproductions\/","https:\/\/www.youtube.com\/@ARDO_PRODUCTIONS"]}]}},"_links":{"self":[{"href":"https:\/\/somosardo.com\/es\/wp-json\/wp\/v2\/projecte\/379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/somosardo.com\/es\/wp-json\/wp\/v2\/projecte"}],"about":[{"href":"https:\/\/somosardo.com\/es\/wp-json\/wp\/v2\/types\/projecte"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/somosardo.com\/es\/wp-json\/wp\/v2\/media\/383"}],"wp:attachment":[{"href":"https:\/\/somosardo.com\/es\/wp-json\/wp\/v2\/media?parent=379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}