{"id":438,"date":"2026-08-31T23:50:54","date_gmt":"2026-08-31T21:50:54","guid":{"rendered":"https:\/\/somosardo.com\/projectes\/libacions\/"},"modified":"2026-09-02T21:27:47","modified_gmt":"2026-09-02T19:27:47","slug":"libacions","status":"publish","type":"projecte","link":"https:\/\/somosardo.com\/es\/projectes\/libacions\/","title":{"rendered":"Libacions"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Texto: Anna Dot<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Sinopsis<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En la antigua Grecia, una libaci\u00f3n era un gesto cotidiano: derramar un poco de agua o vino en el suelo en memoria de los que ya no est\u00e1n. Se hac\u00eda con unas copas planas llamadas p\u00e1teras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre 2022 y 2024, Anna Dot dise\u00f1\u00f3 pateras de cer\u00e1mica y las llen\u00f3 con agua de r\u00edos que desaparecen. Tres veces \u2014en Par\u00eds, en Navarra y en el Empord\u00e0\u2014 camin\u00f3 hasta que el agua se hab\u00eda derramado toda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El v\u00eddeo documenta la segunda.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Nota de direcci\u00f3n<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Las p\u00e1teras de la segunda libaci\u00f3n se hicieron tomando el relevo del cauce del Ter en uno de los d\u00edas de sequ\u00eda. Las llenamos con agua del Ultzama a su paso por el Bat\u00e1n de Villava y la transportamos hasta donde Ultzama desaparece dentro del Arga. El agua se derramaba mientras and\u00e1bamos. Las libaciones se hac\u00edan en honor al Ter, cada vez m\u00e1s desaparecido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La primera hab\u00eda sido en Par\u00eds en octubre de 2022, con agua de La Bi\u00e8vre recogida en un parque de Antony, justo antes de que el r\u00edo pase a ser subterr\u00e1neo, y una caminata por las calles construidas encima hasta el Sena. La tercera, en el Empord\u00e0 en agosto de 2024, sigui\u00f3 un brazo antiguo del Ter hasta su desembocadura en Sant Mart\u00ed d&#8217;Emp\u00faries.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Traje la c\u00e1mara y segu\u00ed la caminata entera, desde que se llenaron las p\u00e1teras hasta que se derram\u00f3 la \u00faltima agua.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Bat\u00e1n de Villava, Navarra, 10 de septiembre de 2023. Exposici\u00f3n \u00c2\u00abLa par\u00e1bola de los ciegos\u00c2\u00bb, para Mapamundistas \/ El Umbral.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"featured_media":439,"menu_order":6,"template":"","class_list":["post-438","projecte","type-projecte","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Libacions &#183; Ardo Productions<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Libacions &#183; Ardo Productions\" \/>\n<meta property=\"og:description\" content=\"Texto: Anna Dot Sinopsis En la antigua Grecia, una libaci\u00f3n era un gesto cotidiano: derramar un poco de agua o vino en el suelo en memoria de los que ya no est\u00e1n. Se hac\u00eda con unas copas planas llamadas p\u00e1teras. Entre 2022 y 2024, Anna Dot dise\u00f1\u00f3 pateras de cer\u00e1mica y las llen\u00f3 con agua [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/somosardo.com\/es\/projectes\/libacions\/\" \/>\n<meta property=\"og:site_name\" content=\"Ardo Productions\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T19:27:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/somosardo.com\/wp-content\/uploads\/2026\/08\/Libacions-Portada-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/somosardo.com\\\/es\\\/projectes\\\/libacions\\\/\",\"url\":\"https:\\\/\\\/somosardo.com\\\/es\\\/projectes\\\/libacions\\\/\",\"name\":\"Libacions &#183; Ardo Productions\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/somosardo.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/somosardo.com\\\/es\\\/projectes\\\/libacions\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/somosardo.com\\\/es\\\/projectes\\\/libacions\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/somosardo.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Libacions-Portada-scaled.jpg\",\"datePublished\":\"2026-08-31T21:50:54+00:00\",\"dateModified\":\"2026-09-02T19:27:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/somosardo.com\\\/es\\\/projectes\\\/libacions\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/somosardo.com\\\/es\\\/projectes\\\/libacions\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/somosardo.com\\\/es\\\/projectes\\\/libacions\\\/#primaryimage\",\"url\":\"https:\\\/\\\/somosardo.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Libacions-Portada-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/somosardo.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Libacions-Portada-scaled.jpg\",\"width\":2560,\"height\":1440,\"caption\":\"Un riu entre el bosc amb el t\u00edtol Libacions i el nom d'Anna Dot\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/somosardo.com\\\/es\\\/projectes\\\/libacions\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/somosardo.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projectes\",\"item\":\"https:\\\/\\\/somosardo.com\\\/es\\\/projectes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Libacions\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/somosardo.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/somosardo.com\\\/es\\\/\",\"name\":\"Ardo Productions\",\"description\":\"Productora audiovisual\",\"publisher\":{\"@id\":\"https:\\\/\\\/somosardo.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/somosardo.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/somosardo.com\\\/es\\\/#organization\",\"name\":\"Ardo Productions\",\"url\":\"https:\\\/\\\/somosardo.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/somosardo.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/somosardo.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/favicon.png\",\"contentUrl\":\"https:\\\/\\\/somosardo.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/favicon.png\",\"width\":600,\"height\":600,\"caption\":\"Ardo Productions\"},\"image\":{\"@id\":\"https:\\\/\\\/somosardo.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/ardoproductions\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@ARDO_PRODUCTIONS\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Libacions &#183; Ardo Productions","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"Libacions &#183; Ardo Productions","og_description":"Texto: Anna Dot Sinopsis En la antigua Grecia, una libaci\u00f3n era un gesto cotidiano: derramar un poco de agua o vino en el suelo en memoria de los que ya no est\u00e1n. Se hac\u00eda con unas copas planas llamadas p\u00e1teras. Entre 2022 y 2024, Anna Dot dise\u00f1\u00f3 pateras de cer\u00e1mica y las llen\u00f3 con agua [&hellip;]","og_url":"https:\/\/somosardo.com\/es\/projectes\/libacions\/","og_site_name":"Ardo Productions","article_modified_time":"2026-09-02T19:27:47+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/somosardo.com\/wp-content\/uploads\/2026\/08\/Libacions-Portada-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/somosardo.com\/es\/projectes\/libacions\/","url":"https:\/\/somosardo.com\/es\/projectes\/libacions\/","name":"Libacions &#183; Ardo Productions","isPartOf":{"@id":"https:\/\/somosardo.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/somosardo.com\/es\/projectes\/libacions\/#primaryimage"},"image":{"@id":"https:\/\/somosardo.com\/es\/projectes\/libacions\/#primaryimage"},"thumbnailUrl":"https:\/\/somosardo.com\/wp-content\/uploads\/2026\/08\/Libacions-Portada-scaled.jpg","datePublished":"2026-08-31T21:50:54+00:00","dateModified":"2026-09-02T19:27:47+00:00","breadcrumb":{"@id":"https:\/\/somosardo.com\/es\/projectes\/libacions\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/somosardo.com\/es\/projectes\/libacions\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/somosardo.com\/es\/projectes\/libacions\/#primaryimage","url":"https:\/\/somosardo.com\/wp-content\/uploads\/2026\/08\/Libacions-Portada-scaled.jpg","contentUrl":"https:\/\/somosardo.com\/wp-content\/uploads\/2026\/08\/Libacions-Portada-scaled.jpg","width":2560,"height":1440,"caption":"Un riu entre el bosc amb el t\u00edtol Libacions i el nom d'Anna Dot"},{"@type":"BreadcrumbList","@id":"https:\/\/somosardo.com\/es\/projectes\/libacions\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/somosardo.com\/es\/"},{"@type":"ListItem","position":2,"name":"Projectes","item":"https:\/\/somosardo.com\/es\/projectes\/"},{"@type":"ListItem","position":3,"name":"Libacions"}]},{"@type":"WebSite","@id":"https:\/\/somosardo.com\/es\/#website","url":"https:\/\/somosardo.com\/es\/","name":"Ardo Productions","description":"Productora audiovisual","publisher":{"@id":"https:\/\/somosardo.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/somosardo.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/somosardo.com\/es\/#organization","name":"Ardo Productions","url":"https:\/\/somosardo.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/somosardo.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/somosardo.com\/wp-content\/uploads\/2026\/06\/favicon.png","contentUrl":"https:\/\/somosardo.com\/wp-content\/uploads\/2026\/06\/favicon.png","width":600,"height":600,"caption":"Ardo Productions"},"image":{"@id":"https:\/\/somosardo.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/ardoproductions\/","https:\/\/www.youtube.com\/@ARDO_PRODUCTIONS"]}]}},"_links":{"self":[{"href":"https:\/\/somosardo.com\/es\/wp-json\/wp\/v2\/projecte\/438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/somosardo.com\/es\/wp-json\/wp\/v2\/projecte"}],"about":[{"href":"https:\/\/somosardo.com\/es\/wp-json\/wp\/v2\/types\/projecte"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/somosardo.com\/es\/wp-json\/wp\/v2\/media\/439"}],"wp:attachment":[{"href":"https:\/\/somosardo.com\/es\/wp-json\/wp\/v2\/media?parent=438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}